{"id":60153,"date":"2020-04-19T07:39:11","date_gmt":"2020-04-19T07:39:11","guid":{"rendered":"https:\/\/www.alj.com\/spotlight-by-fady-jameel\/turning-the-tide\/"},"modified":"2021-03-22T14:28:26","modified_gmt":"2021-03-22T14:28:26","slug":"turning-the-tide","status":"publish","type":"spotlight-fadyjameel","link":"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/","title":{"rendered":"Cambiando la marea"},"content":{"rendered":"<h4>Leonardo da Vinci describi\u00f3 el agua como \u201cla fuerza motriz de toda la naturaleza\u201d. Sin embargo, hoy nuestros ecosistemas marinos penden de un hilo y est\u00e1 bajo una amenaza constante y creciente. \u00bfQu\u00e9 est\u00e1 causando tantos problemas? \u00bfPor qu\u00e9 es tan urgente rectificar la situaci\u00f3n y qu\u00e9 medidas podemos tomar?<\/h4>\n<p><em>Por <\/em><a href=\"https:\/\/alj.com\/es\/our-people\/fady-jameel\/\"><em>Fady Jameel<\/em><\/a><em>, presidente adjunto y vicepresidente, Abdul Latif Jameel<\/em><\/p>\n<p>Los oc\u00e9anos equivalen al 70\u00a0% del planeta, cubren la asombrosa cifra de 362\u00a0millones de kil\u00f3metros cuadrados y suministran m\u00e1s de la mitad del ox\u00edgeno del mundo.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><sup>, <\/sup><a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>. Desde los albores de la historia, los oc\u00e9anos han permitido el comercio entre los pa\u00edses de Oriente y Occidente, han llevado a los exploradores a descubrir nuevos continentes y han sido una de nuestras principales fuentes de sustento. En la actualidad, el mar sigue siendo el motor econ\u00f3mico de muchas comunidades costeras y la vida marina contin\u00faa proporcionando nutrientes esenciales para una dieta saludable, particularmente en los pa\u00edses menos desarrollados.<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>.<\/p>\n<figure id=\"attachment_60103\" aria-describedby=\"caption-attachment-60103\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-60103 size-full\" src=\"https:\/\/www.alj.com\/app\/uploads\/2020\/04\/ALJ-Fish-Health-Benefits.jpg\" alt=\"The Health Benefits Of Eating Fish\" width=\"2560\" height=\"1674\" \/><figcaption id=\"caption-attachment-60103\" class=\"wp-caption-text\"><span style=\"font-size: 12px;\">Pie de foto: El pescado proporciona importantes beneficios para la salud y sigue siendo una fuente esencial de prote\u00ednas y micronutrientes.<\/span><\/figcaption><\/figure>\n<p>Pese a todo, nuestros oc\u00e9anos y la vida marina est\u00e1n amenazados. Durante el siglo pasado, la temperatura del agua aument\u00f3 en torno a 0,1\u00a0\u00baC<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>. A primera vista, esta cifra puede parecer insignificante, pero ya est\u00e1 afectando a la biodiversidad del oc\u00e9ano. Por ejemplo, los arrecifes de coral, que dan cobijo y protecci\u00f3n a miles de especies acu\u00e1ticas,<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a> est\u00e1n bajo amenaza, ya que el aumento de la temperatura mata las algas que los mantienen vivos<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a>.<\/p>\n<p>En los sistemas acu\u00e1ticos de agua dulce el problema es a\u00fan mayor. Seg\u00fan el Fondo Mundial para la Naturaleza (<a href=\"https:\/\/www.worldwildlife.org\/\">WWF<\/a>), los r\u00edos, lagos y humedales de agua dulce contienen el 10\u00a0% de todas las especies marinas, con m\u00e1s diversidad por kil\u00f3metro cuadrado que los oc\u00e9anos o la tierra firme<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a>. Sin embargo, las intervenciones del ser humano, como la contaminaci\u00f3n, las presas artificiales, la sobrepesca y la extracci\u00f3n de arena est\u00e1n minando tanto su diversidad como su abundancia.<\/p>\n<h2>Aumento del nivel del mar<\/h2>\n<p>El Panel Intergubernamental del Cambio Clim\u00e1tico de las Naciones Unidas (<a href=\"https:\/\/www.ipcc.ch\/\">IPCC<\/a>) estima que, entre 2081 y 2100, la temperatura del agua podr\u00eda aumentar entre 0,40 y 0,63\u00a0\u00baC, en escenarios de bajas o altas emisiones respectivamente<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a>. Desde un punto de vista cient\u00edfico, el agua m\u00e1s fr\u00eda puede absorber m\u00e1s di\u00f3xido de carbono (CO<sub>2<\/sub>) Esto quiere decir que, a medida que los oc\u00e9anos se calientan, retienen menos CO<sub>2<\/sub>, que permanece en la atm\u00f3sfera<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a>.<\/p>\n<p>El mismo principio se aplica al aumento del nivel del mar, causado por el crecimiento del volumen de agua. La expansi\u00f3n t\u00e9rmica impulsada por la temperatura aumenta los vol\u00famenes globales del agua del mar, incluso sin tener en cuenta el volumen adicional resultante del deshielo de los casquetes polares, que har\u00e1 que los niveles del mar crezcan a\u00fan m\u00e1s. Y el problema se est\u00e1 acelerando. Se cree que el nivel del mar ha aumentado entre 13 y 20\u00a0cm desde 1900. Para 2100, se prev\u00e9 que aumente entre 30\u00a0cm y 1\u00a0metro.<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a>.<\/p>\n<p>Ya somos testigo de los efectos del aumento del nivel del mar en vista de las cada vez m\u00e1s frecuentes inundaciones costeras.<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a>. Se estima que, para 2050, los 300\u00a0millones de personas que viven en zonas costeras experimentar\u00e1n inundaciones al menos una vez al a\u00f1o, a menos que las emisiones de carbono se reduzcan considerablemente y se fortalezcan las defensas costeras<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a>.<\/p>\n<p><a href=\"https:\/\/sealevel.climatecentral.org\/\">Climate Central<\/a> ha publicado un mapa topol\u00f3gico interactivo en <a href=\"https:\/\/coastal.climatecentral.org\/map\">https:\/\/coastal.climatecentral.org\/map<\/a>, basado en datos cient\u00edficos revisados por expertos, para intentar comprender y cuantificar las \u00e1reas en riesgo.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/CW0D9XTgiGs\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-60110 size-full alignnone\" src=\"https:\/\/www.alj.com\/app\/uploads\/2020\/04\/ALJ-Flood-Risks.jpg\" alt=\"People at risk of annual flooding by 2050\" width=\"2560\" height=\"1724\" \/><\/p>\n<p>La protecci\u00f3n de nuestras zonas costeras tambi\u00e9n se ve socavada por el agotamiento de los arrecifes de coral.<a href=\"#_ftn13\" name=\"_ftnref13\">[13]<\/a>. Cientos de millones de personas dependen de los arrecifes de coral para obtener una nutrici\u00f3n esencial, sustento, protecci\u00f3n contra tormentas que amenazan su vida y oportunidades econ\u00f3micas cruciales. Son un eslab\u00f3n fundamental en la cadena de suministro de alimentos de origen marino. Seg\u00fan datos de WWF, los arrecifes de coral ocupan \u00fanicamente el 0,1\u00a0% del \u00e1rea del oc\u00e9ano, pero sustentan al 25\u00a0% de todas las especies marinas del planeta. De hecho, la biodiversidad asociada con los arrecifes de coral rivaliza con la de los bosques tropicales del Amazonas o Nueva Guinea.<a href=\"#_ftn14\" name=\"_ftnref14\">[14]<\/a>.<\/p>\n<p>La concentraci\u00f3n de arrecifes de coral m\u00e1s grande del mundo, la Gran Barrera de Coral, frente a las costas de Australia, comprende m\u00e1s de 2900 arrecifes individuales y 900\u00a0islas que abarcan m\u00e1s de 2300\u00a0kil\u00f3metros. Al igual que muchos de los miles de sistemas de arrecifes en todo el mundo, tambi\u00e9n est\u00e1 en grave peligro. Boston Consulting Group (BCG) estima que, si no actuamos r\u00e1pido, nuestros oc\u00e9anos podr\u00edan quedarse sin arrecifes de coral para 2050<a href=\"#_ftn15\" name=\"_ftnref15\"><sup>[15]<\/sup><\/a>.<\/p>\n<p>Para las criaturas terrestres que habitan en la costa, el aumento del nivel del mar significa que las \u00e1reas circundantes de agua dulce se est\u00e1n volviendo m\u00e1s salinas, lo que pone en riesgo la vida de especies como las tortugas y las aves marinas.<a href=\"#_ftn16\" name=\"_ftnref16\">[16]<\/a>. Esto tambi\u00e9n tiene un impacto significativo en la disponibilidad de agua dulce para el consumo humano.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-60117 size-full\" src=\"https:\/\/www.alj.com\/app\/uploads\/2020\/04\/ALJ-Sea-Levels.jpg\" alt=\"\" width=\"2560\" height=\"1674\" \/><\/p>\n<h2>Pescando problemas<\/h2>\n<p>El aumento de la temperatura del mar tambi\u00e9n est\u00e1 afectando a la industria pesquera, ya que la vida marina migra fuera de sus h\u00e1bitats naturales hacia aguas m\u00e1s fr\u00edas. Esto significa que las flotas pesqueras necesitan recorrer distancias mucho m\u00e1s largas para lograr capturas, lo que supone una mayor inversi\u00f3n de tiempo, dinero y energ\u00eda, que a su vez deriva en m\u00e1s combustible y carbono en el oc\u00e9ano y la atm\u00f3sfera. Algunos han recurrido al uso de datos clim\u00e1ticos para que sus expediciones sean m\u00e1s efectivas. Otros est\u00e1n apostando por la \u201cacuicultura\u201d (cultivo de vida marina en condiciones controladas) o los criaderos (donde se cr\u00edan y cuidan peces que luego se liberan en aguas naturales)<a href=\"#_ftn17\" name=\"_ftnref17\">[17]<\/a>.<\/p>\n<p>Por si esto fuera poco, el 90\u00a0% de los bancos de pescado est\u00e1n amenazados, ya sea porque han alcanzado su m\u00e1xima capacidad o por la sobrepesca.<a href=\"#_ftn18\" name=\"_ftnref18\">[18]<\/a>. El bacalao, el pez espada y los tiburones son solo algunos ejemplos de especies cuya supervivencia est\u00e1 en peligro. Los arrastreros han sido objeto de un escrutinio particular, debido a sus t\u00e9cnicas de \u201cdragado\u201d, que capturan grandes cantidades de peces para despu\u00e9s acabar descartando cantidades significativas. Los barcos de arrastre tambi\u00e9n da\u00f1an los ecosistemas marinos, en lo que la aclamada bi\u00f3loga marina, Silvia Earle, denomina un enfoque de \u201cbulldozer\u201d. Ella sugiere que debemos ser m\u00e1s conscientes del \u201ccoste real\u201d de nuestras actividades pesqueras y tomar mejores decisiones<a href=\"#_ftn19\" name=\"_ftnref19\">[19]<\/a>.<\/p>\n<p>El <a href=\"https:\/\/www.msc.org\/home\">Marine Stewardship Council<\/a> (MSC) ha desarrollado un modelo de pesca sostenible y lo que describe como un est\u00e1ndar de medici\u00f3n basado en la ciencia para el sector pesquero. Sugiere tres medidas para la pesca sostenible:<\/p>\n<ol>\n<li>Pescar a un nivel que pueda continuar indefinidamente y mantener la poblaci\u00f3n de peces productiva y saludable.<\/li>\n<li>Gestionar las actividades pesqueras para reducir su impacto ambiental y mantener la salud de otras especies y h\u00e1bitats dentro del ecosistema.<\/li>\n<li>Las explotaciones pesqueras deben administrar sus operaciones de manera que cumplan con las leyes relevantes y puedan adaptarse a las circunstancias ambientales cambiantes.<\/li>\n<\/ol>\n<h2>La pandemia del pl\u00e1stico<\/h2>\n<p>Por si los efectos del cambio clim\u00e1tico no fuesen suficiente, otra amenaza sin precedentes para el ecosistema marino es la gran cantidad de desechos pl\u00e1sticos que terminan en nuestros oc\u00e9anos. Se estima que, en total, hay alrededor de 150\u00a0toneladas m\u00e9tricas en todo el mundo,<a href=\"#_ftn20\" name=\"_ftnref20\">[20]<\/a> que actualmente crecen a un ritmo de aproximadamente ocho millones de toneladas al a\u00f1o. Alrededor del 80\u00a0% proviene de fuentes terrestres, a causa de una conciencia y una recolecci\u00f3n para el reciclaje deficientes. Los desechos pl\u00e1sticos amenazan a unas 600\u00a0especies oce\u00e1nicas diferentes, que a menudo lo ingieren confundi\u00e9ndolo con alimento.<a href=\"#_ftn21\" name=\"_ftnref21\">[21]<\/a>.Tambi\u00e9n hay una creciente preocupaci\u00f3n por los \u201cmicropl\u00e1sticos\u201d. Se trata de peque\u00f1as part\u00edculas de pl\u00e1stico, casi indiscernibles en el agua, que son ingeridas por la vida marina en todos los niveles de la cadena alimentaria, incluidos los peces, que luego consumimos los humanos y otros animales terrestres.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-60131 size-full\" src=\"https:\/\/www.alj.com\/app\/uploads\/2020\/04\/ALJ-Plastic-Polution.jpg\" alt=\"Plastic Pandemic\" width=\"2560\" height=\"1724\" \/><\/p>\n<p>La consultora McKinsey estima que, seg\u00fan las tendencias actuales, podr\u00edamos llegar a los 250\u00a0millones de toneladas m\u00e9tricas para 2025, lo que se traduce en que habr\u00eda una tonelada de pl\u00e1stico por cada tres toneladas de pescado<a href=\"#_ftn22\" name=\"_ftnref22\">[22]<\/a>. Sugiere una serie de pasos para combatir el problema, que incluyen: establecer objetivos de gesti\u00f3n de residuos significativos y ensayados a nivel gubernamental, transferir la experiencia global y las mejores pr\u00e1cticas a las ciudades con mayor prioridad, garantizar las condiciones de inversi\u00f3n adecuadas para el proyecto y equipar a los proveedores de tecnolog\u00eda con datos detallados para abordar el problema<a href=\"#_ftn23\" name=\"_ftnref23\">[23]<\/a>.<\/p>\n<h2>El estudio de viabilidad para gestionar el medio marino<\/h2>\n<p>Para los m\u00e1s esc\u00e9pticos, quiz\u00e1s la raz\u00f3n de peso para proteger la vida de nuestros oc\u00e9anos se reduzca a la econom\u00eda b\u00e1sica. BCG describe el oc\u00e9ano como una \u201cpotencia econ\u00f3mica\u201d. Efectivamente, ser\u00eda la s\u00e9ptima econom\u00eda m\u00e1s grande del mundo, con un valor de m\u00e1s de 24\u00a0billones de USD, en particular gracias a que proporciona sustento y crea empleos en \u00e1reas como la pesca, el turismo y el transporte mar\u00edtimo.<a href=\"#_ftn24\" name=\"_ftnref24\">[24]<\/a>.<\/p>\n<p>Al mismo tiempo, m\u00e1s de dos tercios de la econom\u00eda marina dependen del mantenimiento de unos activos saludables. BCG toma como ejemplo el Mar Mediterr\u00e1neo, que ba\u00f1a las costas de 21\u00a0pa\u00edses de Europa, \u00c1frica y Asia, y del que viven m\u00e1s de 150\u00a0millones de personas a lo largo de sus costas.<\/p>\n<p>Sin embargo, mientras que billones de d\u00f3lares en bienes y servicios fluyen hacia y desde nuestras costas, los activos oce\u00e1nicos siguen siendo explotados y se agotan cada vez m\u00e1s. Al no abordar cuestiones como el cambio clim\u00e1tico, la sobrepesca y el agotamiento de h\u00e1bitats marinos, como los arrecifes de coral y los manglares, estamos <em>\u201cdesprestigiando la base de la capital del oc\u00e9ano\u201d<\/em>.<\/p>\n<p>En su informe de 2015 en colaboraci\u00f3n con el WWF,<a href=\"https:\/\/wwf.panda.org\/?245010\/REPORT-Reviving-the-Ocean-Economy-The-case-for-action---2015\"><em> Reviving the Ocean Economy: A Case for Action<\/em><\/a><a href=\"#_ftn25\" name=\"_ftnref25\">[25]<\/a>, BCG ya hab\u00eda propuesto ocho causas de acci\u00f3n para curar los activos oce\u00e1nicos en cuatro pilares que se muestran a continuaci\u00f3n: \u201cobjetivos significativos\u201d, \u201centrega de pol\u00edticas\u201d, \u201cgobernanza responsable\u201d y \u201cdecisiones informadas e intercambio de conocimientos\u201d.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-60124 size-full\" src=\"https:\/\/www.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets.jpg\" alt=\"Eight Actions to secure our ocean assets\" width=\"2480\" height=\"2480\" srcset=\"https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets.jpg 2480w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-300x300.jpg 300w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-1024x1024.jpg 1024w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-150x150.jpg 150w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-768x768.jpg 768w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-1536x1536.jpg 1536w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-2048x2048.jpg 2048w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-200x200.jpg 200w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-170x170.jpg 170w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-70x70.jpg 70w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/ALJ-Ocean-Assets-271x271.jpg 271w\" sizes=\"(max-width: 2480px) 100vw, 2480px\" \/><\/p>\n<h2>Mares compartidos<\/h2>\n<p>El <a href=\"https:\/\/www.unenvironment.org\/\">PNUMA<\/a> participa activamente en la promoci\u00f3n de la protecci\u00f3n y la gesti\u00f3n sostenible de los entornos marinos y costeros del mundo. Su <a href=\"https:\/\/www.unenvironment.org\/explore-topics\/oceans-seas\/what-we-do\/working-regional-seas\/regional-seas-programmes\">Programa de los Mares Regionales<\/a> (RSP) adopta un enfoque de \u201cmares compartidos\u201d, que involucra a los pa\u00edses vecinos para que colaboren en la toma de medidas espec\u00edficas para proteger su medio marino com\u00fan<a href=\"#_ftn26\" name=\"_ftnref26\">[26]<\/a>.<\/p>\n<p>Esto cobra especial relevancia si consideramos que la mayor parte del oc\u00e9ano corresponde a aguas internacionales, fuera de la jurisdicci\u00f3n nacional, o la protecci\u00f3n, de cualquier pa\u00eds en particular<a href=\"#_ftn27\" name=\"_ftnref27\">[27]<\/a>. En la actualidad, m\u00e1s de 143\u00a0pa\u00edses se han unido a 18\u00a0convenciones y planes de acci\u00f3n de Mares Regionales en \u00c1frica Occidental y Oriental, el Caribe, el Mediterr\u00e1neo, el Pac\u00edfico Noroeste, los mares de Asia Oriental y el mar Caspio.<\/p>\n<p>Las iniciativas recientes bajo el esquema de la ONU han incluido un proyecto en Maputo (Mozambique), en la costa sureste de \u00c1frica, donde el pasto marino es esencial para el sustento de las gambas, los pepinos de mar, las almejas y los cangrejos, importantes fuentes de alimentos y de empleo para la comunidad local. Sin embargo, la destructiva recolecci\u00f3n de mariscos ha acabado con el 86\u00a0% de sus praderas de pastos marinos. Se ha puesto en marcha un programa, iniciado por la <a href=\"https:\/\/www.uem.mz\/\">Universidad Eduardo Mondlane<\/a> y con el apoyo del gobierno de Mozambique, para educar a la comunidad local sobre pr\u00e1cticas de pesca no destructivas, que tambi\u00e9n ayudar\u00e1n a cultivar mariscos en los lechos de pastos marinos.<a href=\"#_ftn28\" name=\"_ftnref28\">[28]<\/a>.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-60138 size-thumbnail\" src=\"https:\/\/www.alj.com\/app\/uploads\/2020\/04\/Green-fins-150x116.png\" alt=\"Green Fins Logo\" width=\"150\" height=\"116\" srcset=\"https:\/\/media.alj.com\/app\/uploads\/2020\/04\/Green-fins-150x116.png 150w, https:\/\/media.alj.com\/app\/uploads\/2020\/04\/Green-fins.png 170w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>Conocida como la \u201cAldea de Coral\u201d, Onna Village en Okinawa, Jap\u00f3n, es famosa por sus arrecifes, que atraen a buceadores de todo el mundo. Aunque el turismo del buceo es beneficioso para la econom\u00eda de Onna Village, no es tan bueno para los arrecifes. Como respuesta, se ha unido a <a href=\"https:\/\/www.greenfins.net\/\">\u201cAletas Verdes\u201d<\/a>, un programa de c\u00f3digo de conducta liderado por el PNUMA que proporciona formaci\u00f3n y recursos para los operadores de actividades de buceo y snorkel. El programa, que comenz\u00f3 en 1999 con <a href=\"https:\/\/reef-world.org\/\">Reef World Foundation<\/a>, una organizaci\u00f3n ben\u00e9fica con sede en el Reino Unido, se est\u00e1 llevando a cabo junto con un proyecto local de recuperaci\u00f3n continua que ya ha plantado 30\u00a0000 corales<a href=\"#_ftn29\" name=\"_ftnref29\">[29]<\/a>.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/CLQgvP4TKa4\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Las pr\u00e1cticas agr\u00edcolas y los planes de desarrollo costeros tambi\u00e9n est\u00e1n agotando nuestros bosques de manglares, que se cree que son capaces de almacenar hasta cuatro veces m\u00e1s carbono que los bosques tropicales, por ejemplo. En ciertas \u00e1reas, como Vietnam e India, ya se ha destruido m\u00e1s del 50\u00a0% del terreno hist\u00f3rico de los manglares<a href=\"#_ftn30\" name=\"_ftnref30\">[30]<\/a>. Entre los proyectos de preservaci\u00f3n de manglares que hay en marcha se encuentra una iniciativa en Velondriake, Madagascar, cuyo objetivo es restaurar y conservar m\u00e1s de 1200 hect\u00e1reas de bosque<a href=\"#_ftn31\" name=\"_ftnref31\">[31]<\/a>.<\/p>\n<p>A partir de enero de 2020, las regulaciones de la Organizaci\u00f3n Mar\u00edtima Internacional (<a href=\"https:\/\/www.imo.org\/\">OMI<\/a>) han reducido las emisiones permisibles de azufre de los buques marinos en aguas internacionales del m\u00e1ximo anterior de 3,5\u00a0% hasta tan solo un 0,5\u00a0%. Esta reducci\u00f3n en el contenido de azufre, que excede el 80\u00a0%, es la mayor realizada para un combustible de transporte de una sola vez<a href=\"#_ftn32\" name=\"_ftnref32\">[32]<\/a>. Esto disminuir\u00e1 significativamente la cantidad de \u00f3xidos de azufre que emanan de los barcos y deber\u00eda tener importantes beneficios para la salud y el medio ambiente del planeta, en especial para las poblaciones que viven cerca de puertos y costas.<\/p>\n<h2>Un esfuerzo colaborativo<\/h2>\n<p>Revertir el da\u00f1o colateral que hemos causado hasta ahora en los oc\u00e9anos no ser\u00e1 una tarea f\u00e1cil. Se necesitar\u00e1 un esfuerzo coordinado de empresas, l\u00edderes comunitarios, consumidores y gobiernos.<\/p>\n<p>La <a href=\"https:\/\/www.unwto.org\/sustainable-development\/global-tourism-plastics-initiative\">Iniciativa Mundial sobre Turismo y Pl\u00e1sticos<\/a>, impulsada por la ONU, cuenta con m\u00e1s de 450\u00a0signatarios, entre los que hay empresas, gobiernos y otras organizaciones. Todos ellos est\u00e1n dispuestos a contraer compromisos espec\u00edficos para reducir los pl\u00e1sticos para 2025, a trav\u00e9s de medidas que incluyen la eliminaci\u00f3n de los envases de pl\u00e1stico innecesarios, la transici\u00f3n de los pl\u00e1sticos de un solo uso a pl\u00e1sticos reutilizables, y la supervisi\u00f3n para que todos los envases de pl\u00e1stico sean reciclables o compostables. Se publicar\u00e1n informes p\u00fablicos sobre su progreso anualmente<a href=\"#_ftn33\" name=\"_ftnref33\">[33]<\/a>.<\/p>\n<p>La Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (<a href=\"https:\/\/www.iucn.org\/\">UICN<\/a>) es un organismo ambiental con alrededor de 1300\u00a0miembros, entre los que figuran organismos gubernamentales, organizaciones no gubernamentales y asociaciones empresariales y acad\u00e9micas<a href=\"#_ftn34\" name=\"_ftnref34\">[34]<\/a>. En su Congreso Mundial de la Naturaleza en 2016, sus miembros aprobaron una resoluci\u00f3n para proteger el 30\u00a0% del oc\u00e9ano del planeta para 2030. Hace un llamamiento para apoyar a la investigaci\u00f3n cient\u00edfica en el an\u00e1lisis y la supervisi\u00f3n de los efectos del cambio clim\u00e1tico y utilizar el conocimiento para implementar estrategias de mitigaci\u00f3n apropiadas.<a href=\"#_ftn35\" name=\"_ftnref35\">[35]<\/a>. El pr\u00f3ximo evento, que tiene lugar cada cuatro a\u00f1os, est\u00e1 programado para junio de 2020.<\/p>\n<p>A t\u00edtulo personal, estoy orgulloso de que <a href=\"https:\/\/alj.com\">Abdul Latif Jameel<\/a>, a trav\u00e9s de <a href=\"https:\/\/almarwater.com\">Almar Water Solutions<\/a>, est\u00e9 ayudando a abordar algunos de los problemas relacionados con la disponibilidad y la seguridad de los suministros de agua dulce en comunidades de todo el mundo.<\/p>\n<p>Almar Water Solutions es un proveedor especializado de capacidades t\u00e9cnicas para el desarrollo de infraestructuras hidr\u00e1ulicas, incluido el dise\u00f1o, la financiaci\u00f3n y el desarrollo de las mismas. Ha demostrado ser el complemento ideal para <a href=\"http:\/\/frv.com\">Fotowatio Renewable Ventures<\/a>, la secci\u00f3n de energ\u00eda renovable de <a href=\"https:\/\/www.alj.com\/en\/energy-and-environmental-services\/energy-overview\/\">Abdul Latif Jameel Energy<\/a>.<\/p>\n<p>En enero de 2019, Almar Water Solutions se adjudic\u00f3 el contrato en Arabia Saud\u00ed para desarrollar <a href=\"https:\/\/www.alj.com\/en\/news\/almar-water-solutions-invest-us-600m-supply-1-8m-people-saudi-arabia-desalinated-water\/\">Shuqaiq 3 IWP<\/a>, una de las plantas desalinizadoras de \u00f3smosis inversa m\u00e1s grandes del mundo. Situada cerca de la ciudad de Al Shuqaiq, en el Mar Rojo, una inversi\u00f3n de 600 millones de d\u00f3lares estadounidenses financiar\u00e1 el desarrollo de una planta del tama\u00f1o de 34 campos de f\u00fatbol. Cuando se finalice su construcci\u00f3n en 2021, suministrar\u00e1 450\u00a0000 m<sup>3<\/sup> de agua limpia cada d\u00eda en un plan BOO de 25 a\u00f1os con WEC. M\u00e1s de 1,8 millones de personas recibir\u00e1n agua fresca del lugar, y se crear\u00e1n 700 empleos.<\/p>\n<p>La noticia de nuestra participaci\u00f3n lleg\u00f3 menos de ocho semanas despu\u00e9s de que se nos adjudicara el contrato para producir la primera planta de desalinizaci\u00f3n a gran escala de Kenia. Una vez operativa, la planta suministrar\u00e1 100\u00a0000\u00a0m<sup>3<\/sup> de agua potable a m\u00e1s de un mill\u00f3n de personas en <a href=\"https:\/\/www.alj.com\/en\/perspective\/almar-water-solutions-helps-tackle-kenyan-water-scarcity\/\">Mombasa<\/a>, en la costa de Kenia, donde una severa crisis h\u00eddrica lleva provocando interrupciones en el suministro desde hace varios a\u00f1os.<\/p>\n<h2>La soluci\u00f3n comienza en la tierra<\/h2>\n<p>Como se mencion\u00f3 anteriormente, m\u00e1s del 80\u00a0% de la contaminaci\u00f3n del oc\u00e9ano proviene de actividades terrestres. Adem\u00e1s de los pl\u00e1sticos, se incluyen los vertidos urbanos, los desarrollos costeros, la escorrent\u00eda de pesticidas agr\u00edcolas y los vertidos de f\u00e1bricas y plantas industriales.<a href=\"#_ftn36\" name=\"_ftnref36\">[36]<\/a><sup>, <\/sup><a href=\"#_ftn37\" name=\"_ftnref37\">[37]<\/a>.<\/p>\n<p>National Geographic estima que las plantas de tratamiento de aguas residuales de los Estados Unidos vierten el doble de contaminantes que los petroleros. Tambi\u00e9n destaca que otra amenaza son las algas venenosas y las plantas que entran a las aguas portuarias. Sugiere soluciones como establecer parques marinos para proteger la biodiversidad, reducir las pr\u00e1cticas de pesca de arrastre, minimizar el s\u00f3nar militar que da\u00f1a o mata especies como los delfines y las ballenas, y ayudar a los pescadores a utilizar m\u00e9todos de conservaci\u00f3n que les permitan mantener su forma de vida.<a href=\"#_ftn38\" name=\"_ftnref38\">[38]<\/a>.<\/p>\n<p>Las soluciones son complejas. Pero proteger nuestros oc\u00e9anos deber\u00eda ser uno de los principales temas de la agenda mundial sobre el cambio clim\u00e1tico, especialmente en t\u00e9rminos de seguridad alimentaria e h\u00eddrica. La poblaci\u00f3n mundial actual de 7600\u00a0millones alcanzar\u00e1 los 9800\u00a0millones para 2050 y los 11200\u00a0millones para 2100. Para muchas comunidades, particularmente en los pa\u00edses m\u00e1s pobres, los mares a\u00fan proporcionan una fuente primaria de alimentos, nutrici\u00f3n y creaci\u00f3n de empleo. Hist\u00f3ricamente el oc\u00e9ano se ha visto como una de las formas m\u00e1s efectivas de capturar carbono, pero ahora est\u00e1 llegando a su l\u00edmite y necesita que lo protejamos con urgencia.<\/p>\n<p>Tengo la esperanza de que, si las empresas, los gobiernos, las ONG y las comunidades trabajamos juntos con un esp\u00edritu de colaboraci\u00f3n y acci\u00f3n, podremos salvar nuestros oc\u00e9anos antes de que sea demasiado tarde.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <a href=\"https:\/\/www.weforum.org\/agenda\/2014\/06\/three-ways-can-save-worlds-oceans\">https:\/\/www.weforum.org\/agenda\/2014\/06\/three-ways-can-save-worlds-oceans<\/a><\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <a href=\"\"><\/a><\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> <a href=\"https:\/\/eatforum.org\/content\/uploads\/2019\/11\/Seafood_Scoping_Report_EAT-Lancet.pdf\">https:\/\/eatforum.org\/content\/uploads\/2019\/11\/Seafood_Scoping_Report_EAT-Lancet.pdf<\/a><\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> <a href=\"https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change\">https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change<\/a><\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> <a href=\"https:\/\/www.nhm.ac.uk\/discover\/quick-questions\/why-are-coral-reefs-important.html?gclid=Cj0KCQjw09HzBRDrARIsAG60GP9hNeNmABUXeDcVs2NiWNvNQJXEEuprOW5-Zs00HmfkK_wmQOvu8k0aAopVEALw_wcB\">https:\/\/www.nhm.ac.uk\/discover\/quick-questions\/why-are-coral-reefs-important.html?gclid=Cj0KCQjw09HzBRDrARIsAG60GP9hNeNmABUXeDcVs2NiWNvNQJXEEuprOW5-Zs00HmfkK_wmQOvu8k0aAopVEALw_wcB<\/a><\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> <a href=\"https:\/\/www.weforum.org\/agenda\/2014\/06\/challenges-worlds-oceans\">https:\/\/www.weforum.org\/agenda\/2014\/06\/challenges-worlds-oceans<\/a><\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> <a href=\"https:\/\/smartwatermagazine.com\/news\/wwf\/emergency-recovery-plan-could-halt-catastrophic-collapse-worlds-freshwater-biodiversity\">https:\/\/smartwatermagazine.com\/news\/wwf\/emergency-recovery-plan-could-halt-catastrophic-collapse-worlds-freshwater-biodiversity<\/a><\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> <a href=\"https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change\">https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change<\/a><\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a> <a href=\"https:\/\/www.theguardian.com\/environment\/climate-consensus-97-per-cent\/2017\/feb\/16\/scientists-study-ocean-absorption-of-human-carbon-pollution\">https:\/\/www.theguardian.com\/environment\/climate-consensus-97-per-cent\/2017\/feb\/16\/scientists-study-ocean-absorption-of-human-carbon-pollution<\/a><\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a> <a href=\"https:\/\/ocean.si.edu\/through-time\/ancient-seas\/sea-level-rise\">https:\/\/ocean.si.edu\/through-time\/ancient-seas\/sea-level-rise<\/a><\/p>\n<p><a href=\"#_ftnref11\" name=\"_ftn11\">[11]<\/a> <a href=\"https:\/\/www.bbc.co.uk\/news\/science-environment-51283716\">https:\/\/www.bbc.co.uk\/news\/science-environment-51283716<\/a><\/p>\n<p><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a> <a href=\"https:\/\/www.theguardian.com\/environment\/2019\/oct\/29\/rising-sea-levels-pose-threat-to-homes-of-300m-people-study\">https:\/\/www.theguardian.com\/environment\/2019\/oct\/29\/rising-sea-levels-pose-threat-to-homes-of-300m-people-study<\/a><\/p>\n<p><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a> <a href=\"https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change\">https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change<\/a><\/p>\n<p><a href=\"#_ftnref14\" name=\"_ftn14\">[14]<\/a> <a href=\"https:\/\/wwf.panda.org\/our_work\/oceans\/coasts\/coral_reefs\/\">https:\/\/wwf.panda.org\/our_work\/oceans\/coasts\/coral_reefs\/<\/a><\/p>\n<p><a href=\"#_ftnref15\" name=\"_ftn15\">[15]<\/a> <a href=\"https:\/\/www.bcg.com\/en-gb\/publications\/2017\/transformation-sustainability-economic-imperative-to-revive-our-oceans.aspx\">https:\/\/www.bcg.com\/en-gb\/publications\/2017\/transformation-sustainability-economic-imperative-to-revive-our-oceans.aspx<\/a><\/p>\n<p><a href=\"#_ftnref16\" name=\"_ftn16\">[16]<\/a> <a href=\"https:\/\/www.yaleclimateconnections.org\/2018\/05\/rising-sea-levels-putting-wildlife-at-risk\/\">https:\/\/www.yaleclimateconnections.org\/2018\/05\/rising-sea-levels-putting-wildlife-at-risk\/<\/a><\/p>\n<p><a href=\"#_ftnref17\" name=\"_ftn17\">[17]<\/a> <a href=\"https:\/\/www.yaleclimateconnections.org\/2020\/03\/ocean-fish-swim-away-from-warming-waters\/\">https:\/\/www.yaleclimateconnections.org\/2020\/03\/ocean-fish-swim-away-from-warming-waters\/<\/a><\/p>\n<p><a href=\"#_ftnref18\" name=\"_ftn18\">[18]<\/a> <a href=\"https:\/\/www.weforum.org\/agenda\/2018\/07\/fish-stocks-are-used-up-fisheries-subsidies-must-stop\/\">https:\/\/www.weforum.org\/agenda\/2018\/07\/fish-stocks-are-used-up-fisheries-subsidies-must-stop\/<\/a><\/p>\n<p><a href=\"#_ftnref19\" name=\"_ftn19\">[19]<\/a> <a href=\"https:\/\/marinebio.org\/interview-with-dr-sylvia-earle\/\">https:\/\/marinebio.org\/interview-with-dr-sylvia-earle\/<\/a><\/p>\n<p><a href=\"#_ftnref20\" name=\"_ftn20\">[20]<\/a> <a href=\"https:\/\/www.mckinsey.com\/business-functions\/sustainability\/our-insights\/saving-the-ocean-from-plastic-waste\">https:\/\/www.mckinsey.com\/business-functions\/sustainability\/our-insights\/saving-the-ocean-from-plastic-waste<\/a><\/p>\n<p><a href=\"#_ftnref21\" name=\"_ftn21\">[21]<\/a> <a href=\"https:\/\/www.weforum.org\/agenda\/2019\/01\/we-can-stop-choking-our-oceans-with-plastic-waste-heres-how\/\">https:\/\/www.weforum.org\/agenda\/2019\/01\/we-can-stop-choking-our-oceans-with-plastic-waste-heres-how\/<\/a><\/p>\n<p><a href=\"#_ftnref22\" name=\"_ftn22\">[22]<\/a> <a href=\"https:\/\/www.mckinsey.com\/business-functions\/sustainability\/our-insights\/saving-the-ocean-from-plastic-waste\">https:\/\/www.mckinsey.com\/business-functions\/sustainability\/our-insights\/saving-the-ocean-from-plastic-waste<\/a><\/p>\n<p><a href=\"#_ftnref23\" name=\"_ftn23\">[23]<\/a> <a href=\"https:\/\/www.mckinsey.com\/business-functions\/sustainability\/our-insights\/saving-the-ocean-from-plastic-waste\">https:\/\/www.mckinsey.com\/business-functions\/sustainability\/our-insights\/saving-the-ocean-from-plastic-waste<\/a><\/p>\n<p><a href=\"#_ftnref24\" name=\"_ftn24\">[24]<\/a> <a href=\"https:\/\/www.bcg.com\/en-gb\/publications\/2017\/transformation-sustainability-economic-imperative-to-revive-our-oceans.aspx\">https:\/\/www.bcg.com\/en-gb\/publications\/2017\/transformation-sustainability-economic-imperative-to-revive-our-oceans.aspx<\/a><\/p>\n<p><a href=\"#_ftnref25\" name=\"_ftn25\">[25]<\/a> <a href=\"https:\/\/www.worldwildlife.org\/publications\/reviving-the-oceans-economy-the-case-for-action-2015\">https:\/\/www.worldwildlife.org\/publications\/reviving-the-oceans-economy-the-case-for-action-2015<\/a><\/p>\n<p><a href=\"#_ftnref26\" name=\"_ftn26\">[26]<\/a> <a href=\"https:\/\/www.unenvironment.org\/explore-topics\/oceans-seas\/what-we-do\/working-regional-seas\/why-does-working-regional-seas-matter\">https:\/\/www.unenvironment.org\/explore-topics\/oceans-seas\/what-we-do\/working-regional-seas\/why-does-working-regional-seas-matter<\/a><\/p>\n<p><a href=\"#_ftnref27\" name=\"_ftn27\">[27]<\/a> <a href=\"https:\/\/www.weforum.org\/agenda\/2014\/06\/three-ways-can-save-worlds-oceans\">https:\/\/www.weforum.org\/agenda\/2014\/06\/three-ways-can-save-worlds-oceans<\/a><\/p>\n<p><a href=\"#_ftnref28\" name=\"_ftn28\">[28]<\/a> <a href=\"https:\/\/www.unenvironment.org\/news-and-stories\/story\/saving-mozambiques-seagrass\">https:\/\/www.unenvironment.org\/news-and-stories\/story\/saving-mozambiques-seagrass<\/a><\/p>\n<p><a href=\"#_ftnref29\" name=\"_ftn29\">[29]<\/a> <a href=\"https:\/\/www.unenvironment.org\/news-and-stories\/story\/village-coral-moves-protect-its-namesake\">https:\/\/www.unenvironment.org\/news-and-stories\/story\/village-coral-moves-protect-its-namesake<\/a><\/p>\n<p><a href=\"#_ftnref30\" name=\"_ftn30\">[30]<\/a> <a href=\"https:\/\/smartwatermagazine.com\/news\/wwf\/climate-crisis-mangroves-bring-massive-benefits\">https:\/\/smartwatermagazine.com\/news\/wwf\/climate-crisis-mangroves-bring-massive-benefits<\/a><\/p>\n<p><a href=\"#_ftnref31\" name=\"_ftn31\">[31]<\/a> <a href=\"https:\/\/www.unenvironment.org\/news-and-stories\/story\/greening-blue-championing-coastal-climate-solutions\">https:\/\/www.unenvironment.org\/news-and-stories\/story\/greening-blue-championing-coastal-climate-solutions<\/a><\/p>\n<p><a href=\"#_ftnref32\" name=\"_ftn32\">[32]<\/a> <a href=\"https:\/\/www.woodmac.com\/nslp\/imo-2020-guide\/\">https:\/\/www.woodmac.com\/nslp\/imo-2020-guide\/<\/a><\/p>\n<p><a href=\"#_ftnref33\" name=\"_ftn33\">[33]<\/a> <a href=\"https:\/\/www.unenvironment.org\/news-and-stories\/story\/tourism-tackle-plastic-pollution-new-commitment\">https:\/\/www.unenvironment.org\/news-and-stories\/story\/tourism-tackle-plastic-pollution-new-commitment<\/a><\/p>\n<p><a href=\"#_ftnref34\" name=\"_ftn34\">[34]<\/a> <a href=\"https:\/\/www.iucn.org\/\">https:\/\/www.iucn.org\/<\/a><\/p>\n<p><a href=\"#_ftnref35\" name=\"_ftn35\">[35]<\/a> <a href=\"https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change\">https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change<\/a><\/p>\n<p><a href=\"#_ftnref36\" name=\"_ftn36\">[36]<\/a> <a href=\"https:\/\/www.nationalgeographic.com\/environment\/habitats\/ocean-threats\/\">https:\/\/www.nationalgeographic.com\/environment\/habitats\/ocean-threats\/<\/a><\/p>\n<p><a href=\"#_ftnref37\" name=\"_ftn37\">[37]<\/a> <a href=\"https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change\">https:\/\/www.iucn.org\/resources\/issues-briefs\/ocean-and-climate-change<\/a><\/p>\n<p><a href=\"#_ftnref38\" name=\"_ftn38\">[38]<\/a> <a href=\"https:\/\/www.nationalgeographic.com\/environment\/habitats\/ocean-threats\/\">https:\/\/www.nationalgeographic.com\/environment\/habitats\/ocean-threats\/<\/a><\/p>\n<h3>Con\u00e9ctate conmigo en LinkedIn<\/h3>\n<p><script type=\"text\/javascript\" src=\"https:\/\/platform.linkedin.com\/badges\/js\/profile.js\" async=\"\" defer=\"\"><\/script><\/p>\n<div class=\"LI-profile-badge\" data-version=\"v1\" data-size=\"medium\" data-locale=\"en_US\" data-type=\"horizontal\" data-theme=\"dark\" data-vanity=\"fady-jameel\"><a class=\"LI-simple-link\" href=\"https:\/\/ae.linkedin.com\/in\/fady-jameel?trk=profile-badge\">Fady J.<\/a><\/div>\n","protected":false},"featured_media":60145,"template":"","tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deniz Ekosistemimizi Koruma - Fady Jameel | Abdul Latif Jameel\u00ae<\/title>\n<meta name=\"description\" content=\"Fady Jameel Bak\u0131\u015f, iklim de\u011fi\u015fikli\u011finin ve kara kaynakl\u0131 kirlili\u011fin okyanuslar\u0131m\u0131z ve deniz ya\u015fam\u0131m\u0131z \u00fczerindeki etkisini ara\u015ft\u0131r\u0131yor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deniz Ekosistemimizi Koruma - Fady Jameel | Abdul Latif Jameel\u00ae\" \/>\n<meta property=\"og:description\" content=\"Fady Jameel Bak\u0131\u015f, iklim de\u011fi\u015fikli\u011finin ve kara kaynakl\u0131 kirlili\u011fin okyanuslar\u0131m\u0131z ve deniz ya\u015fam\u0131m\u0131z \u00fczerindeki etkisini ara\u015ft\u0131r\u0131yor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/\" \/>\n<meta property=\"og:site_name\" content=\"Abdul Latif Jameel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Abdul.Latif.Jameel.Official\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-22T14:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.alj.com\/app\/uploads\/2020\/04\/Turning-tide-hero-1024x592.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/\",\"url\":\"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/\",\"name\":\"Deniz Ekosistemimizi Koruma - Fady Jameel | Abdul Latif Jameel\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/alj.com\/en\/#website\"},\"datePublished\":\"2020-04-19T07:39:11+00:00\",\"dateModified\":\"2021-03-22T14:28:26+00:00\",\"description\":\"Fady Jameel Bak\u0131\u015f, iklim de\u011fi\u015fikli\u011finin ve kara kaynakl\u0131 kirlili\u011fin okyanuslar\u0131m\u0131z ve deniz ya\u015fam\u0131m\u0131z \u00fczerindeki etkisini ara\u015ft\u0131r\u0131yor.\",\"breadcrumb\":{\"@id\":\"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/alj.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spotlight By Fady Jameel\",\"item\":\"https:\/\/alj.com\/ja\/spotlight-by-fady-jameel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cambiando la marea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/alj.com\/en\/#website\",\"url\":\"https:\/\/alj.com\/en\/\",\"name\":\"Abdul Latif Jameel\",\"description\":\"Abdul Latif Jameel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/alj.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deniz Ekosistemimizi Koruma - Fady Jameel | Abdul Latif Jameel\u00ae","description":"Fady Jameel Bak\u0131\u015f, iklim de\u011fi\u015fikli\u011finin ve kara kaynakl\u0131 kirlili\u011fin okyanuslar\u0131m\u0131z ve deniz ya\u015fam\u0131m\u0131z \u00fczerindeki etkisini ara\u015ft\u0131r\u0131yor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/","og_locale":"es_ES","og_type":"article","og_title":"Deniz Ekosistemimizi Koruma - Fady Jameel | Abdul Latif Jameel\u00ae","og_description":"Fady Jameel Bak\u0131\u015f, iklim de\u011fi\u015fikli\u011finin ve kara kaynakl\u0131 kirlili\u011fin okyanuslar\u0131m\u0131z ve deniz ya\u015fam\u0131m\u0131z \u00fczerindeki etkisini ara\u015ft\u0131r\u0131yor.","og_url":"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/","og_site_name":"Abdul Latif Jameel","article_publisher":"https:\/\/www.facebook.com\/Abdul.Latif.Jameel.Official","article_modified_time":"2021-03-22T14:28:26+00:00","og_image":[{"width":1024,"height":592,"url":"https:\/\/media.alj.com\/app\/uploads\/2020\/04\/Turning-tide-hero-1024x592.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/","url":"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/","name":"Deniz Ekosistemimizi Koruma - Fady Jameel | Abdul Latif Jameel\u00ae","isPartOf":{"@id":"https:\/\/alj.com\/en\/#website"},"datePublished":"2020-04-19T07:39:11+00:00","dateModified":"2021-03-22T14:28:26+00:00","description":"Fady Jameel Bak\u0131\u015f, iklim de\u011fi\u015fikli\u011finin ve kara kaynakl\u0131 kirlili\u011fin okyanuslar\u0131m\u0131z ve deniz ya\u015fam\u0131m\u0131z \u00fczerindeki etkisini ara\u015ft\u0131r\u0131yor.","breadcrumb":{"@id":"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alj.com\/es\/spotlight-by-fady-jameel\/turning-the-tide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alj.com\/es\/"},{"@type":"ListItem","position":2,"name":"Spotlight By Fady Jameel","item":"https:\/\/alj.com\/ja\/spotlight-by-fady-jameel\/"},{"@type":"ListItem","position":3,"name":"Cambiando la marea"}]},{"@type":"WebSite","@id":"https:\/\/alj.com\/en\/#website","url":"https:\/\/alj.com\/en\/","name":"Abdul Latif Jameel","description":"Abdul Latif Jameel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alj.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"}]}},"post-meta-fields":{"_alp_processed":["1587282527"],"_wpml_word_count":["{\"total\":2683,\"to_translate\":{\"ar\":2683,\"zh-hans\":2683,\"fr\":2683,\"ja\":2683,\"es\":2683,\"tr\":2683}}"],"push_notification":["no"],"_push_notification":["field_5c3b1fb67034d"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"perspective_short_title":["Cambiando la marea"],"perspective_summury":["<p>Leonardo da Vinci describi\u00f3 el agua como \u201cla fuerza motriz de toda la naturaleza\u201d. Sin embargo, hoy nuestros ecosistemas marinos penden de un hilo y est\u00e1 bajo una amenaza constante y creciente. \u00bfQu\u00e9 est\u00e1 causando tantos problemas?<\/p>\n"],"perspective_location":["Dubai, Emiratos \u00c1rabes Unidos"],"perspective_author_name":["<p><span style=\"color: #000000;\"><a href=\"https:\/\/www.alj.com\/es\/our-people\/fady-jameel\/\">Fady Jameel<\/a><\/span><\/p>\n<p>Presidente adjunto y vicepresidente,\u00a0Abdul Latif Jameel International<\/p>\n"],"perspective_author_bio":["<p><a href=\"https:\/\/www.alj.com\/es\/our-people\/fady-jameel\/\">Fady Jameel<\/a> es presidente adjunto y vicepresidente internacional de\u00a0Abdul Latif Jameel, un colectivo de empresas internacionales e independientes diversificadas de propiedad familiar fundado en 1945 por el difunto Abdul Latif Jameel.<\/p>\n"],"wpcf-featured-news":["0"],"is_latest_news":["0"],"wpcf-show-news-at-homepage":["0"],"publish_mobile":[""],"_publish_mobile":["field_5bfa8eb2e65cf"],"mobile_featured_image":["https:\/\/media.alj.com\/app\/uploads\/2020\/04\/Turning-tide-hero.png"],"_mobile_featured_image":["field_5c3b204983dea"],"_wpcf-card-image-sort-order":["a:1:{i:0;i:946036;}"],"_bsf_post_type":["0"],"_bsf_item_review_type":["none"],"_yoast_wpseo_content_score":["30"],"_thumbnail_id":["60145"],"_last_translation_edit_mode":["native-editor"],"_yoast_wpseo_title":["Deniz Ekosistemimizi Koruma - Fady Jameel | Abdul Latif Jameel\u00ae"],"_yoast_wpseo_metadesc":["Fady Jameel Bak\u0131\u015f, iklim de\u011fi\u015fikli\u011finin ve kara kaynakl\u0131 kirlili\u011fin okyanuslar\u0131m\u0131z ve deniz ya\u015fam\u0131m\u0131z \u00fczerindeki etkisini ara\u015ft\u0131r\u0131yor."],"perspective_business_sector":["Energ\u00eda y Servicios Medioambientales","Agua y Soluciones Medioambientales","Community Jameel"],"perspective_author_image":["51686"],"is_podcast":["0"],"_is_podcast":["field_5ee1dff933e7f"],"wpcf-perspective-published-date":["1587340800"],"wpcf-card-image":[""]},"_links":{"self":[{"href":"https:\/\/alj.com\/es\/wp-json\/wp\/v2\/spotlight-fadyjameel\/60153"}],"collection":[{"href":"https:\/\/alj.com\/es\/wp-json\/wp\/v2\/spotlight-fadyjameel"}],"about":[{"href":"https:\/\/alj.com\/es\/wp-json\/wp\/v2\/types\/spotlight-fadyjameel"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alj.com\/es\/wp-json\/wp\/v2\/media\/60145"}],"wp:attachment":[{"href":"https:\/\/alj.com\/es\/wp-json\/wp\/v2\/media?parent=60153"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alj.com\/es\/wp-json\/wp\/v2\/tags?post=60153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}